{"id":16,"count":3,"description":"Objektivfilter sind in mehrfacher Hinsicht ein wichtiges Zubeh\u00f6rst\u00fcck f\u00fcr deine Kamera. Zum einen bieten sie einen Schutz f\u00fcr die recht empfindlichen Linsen \u2013 vor Staub, Kratzern und Fingerabdr\u00fccken, sondern erm\u00f6glichen dir einige Effekte f\u00fcr dein Bild. So reduziert ein Polarisationsfilter Reflexionen von beispielsweise Glasscheiben oder Autolacken.\r\n\r\nDie unterschiedliche Arten von Filtern wirken sich alle anders auf das Foto aus:\r\n\r\n<strong>UV-Filter<\/strong> sch\u00fctzen die Frontlinse der Kamera vor UV-Strahlen, Staub und Kratzern. Sie sind also f\u00fcr den allt\u00e4glichen Schutz und sorgen f\u00fcr klare, scharfe Bilder ohne unerw\u00fcnschte Blaustiche.\r\n\r\n<a href=\"https:\/\/erikdraeger.com\/ratgeber\/grauverlaufsfilter\/\"><strong>Grauverlaufsfilter (ND-Filter)<\/strong><\/a> reduzieren die einfallende Lichtmenge und erm\u00f6glichen so lange Belichtungszeiten oder eine offene Blende auch bei hellem Tageslicht. Sie sind bestens geeignet f\u00fcr kreative Effekte wie weich flie\u00dfendes Wasser oder Bewegungsunsch\u00e4rfe.\r\n\r\n<a href=\"https:\/\/erikdraeger.com\/ratgeber\/polfilter-72mm\/\"><strong>Polarisationsfilter<\/strong> <\/a>minimieren Reflexionen auf metallischen und nichtmetallischen Oberfl\u00e4chen wie Wasser oder Glas und verst\u00e4rken dar\u00fcber hinaus noch die Farben und Kontraste. Sie eignen sich besonders f\u00fcr Landschaftsaufnahmen, Produktfotos oder Aufnahmen bei starkem Sonnenlicht.","link":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/filter\/","name":"Filter","slug":"filter","taxonomy":"category","parent":10,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Filter Archive - Erik Draeger Photography<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/filter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filter Archive - Erik Draeger Photography\" \/>\n<meta property=\"og:description\" content=\"Objektivfilter sind in mehrfacher Hinsicht ein wichtiges Zubeh\u00f6rst\u00fcck f\u00fcr deine Kamera. Zum einen bieten sie einen Schutz f\u00fcr die recht empfindlichen Linsen \u2013 vor Staub, Kratzern und Fingerabdr\u00fccken, sondern erm\u00f6glichen dir einige Effekte f\u00fcr dein Bild. So reduziert ein Polarisationsfilter Reflexionen von beispielsweise Glasscheiben oder Autolacken. Die unterschiedliche Arten von Filtern wirken sich alle anders auf das Foto aus: UV-Filter sch\u00fctzen die Frontlinse der Kamera vor UV-Strahlen, Staub und Kratzern. Sie sind also f\u00fcr den allt\u00e4glichen Schutz und sorgen f\u00fcr klare, scharfe Bilder ohne unerw\u00fcnschte Blaustiche. Grauverlaufsfilter (ND-Filter) reduzieren die einfallende Lichtmenge und erm\u00f6glichen so lange Belichtungszeiten oder eine offene Blende auch bei hellem Tageslicht. Sie sind bestens geeignet f\u00fcr kreative Effekte wie weich flie\u00dfendes Wasser oder Bewegungsunsch\u00e4rfe. Polarisationsfilter minimieren Reflexionen auf metallischen und nichtmetallischen Oberfl\u00e4chen wie Wasser oder Glas und verst\u00e4rken dar\u00fcber hinaus noch die Farben und Kontraste. Sie eignen sich besonders f\u00fcr Landschaftsaufnahmen, Produktfotos oder Aufnahmen bei starkem Sonnenlicht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/filter\/\" \/>\n<meta property=\"og:site_name\" content=\"Erik Draeger Photography\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/category\\\/zubehoer\\\/filter\\\/\",\"url\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/category\\\/zubehoer\\\/filter\\\/\",\"name\":\"Filter Archive - Erik Draeger Photography\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/category\\\/zubehoer\\\/filter\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/category\\\/zubehoer\\\/filter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zubeh\u00f6r\",\"item\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/category\\\/zubehoer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Filter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#website\",\"url\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/\",\"name\":\"Erik Draeger Photography\",\"description\":\"Ratgeber f\u00fcr Kamera, Objektiv &amp; Zubeh\u00f6r\",\"publisher\":{\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#organization\",\"name\":\"Erik Draeger Photography\",\"url\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-ed-ratgeber-title-2-inverted.jpg\",\"contentUrl\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-ed-ratgeber-title-2-inverted.jpg\",\"width\":1051,\"height\":211,\"caption\":\"Erik Draeger Photography\"},\"image\":{\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filter Archive - Erik Draeger Photography","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/filter\/","og_locale":"de_DE","og_type":"article","og_title":"Filter Archive - Erik Draeger Photography","og_description":"Objektivfilter sind in mehrfacher Hinsicht ein wichtiges Zubeh\u00f6rst\u00fcck f\u00fcr deine Kamera. Zum einen bieten sie einen Schutz f\u00fcr die recht empfindlichen Linsen \u2013 vor Staub, Kratzern und Fingerabdr\u00fccken, sondern erm\u00f6glichen dir einige Effekte f\u00fcr dein Bild. So reduziert ein Polarisationsfilter Reflexionen von beispielsweise Glasscheiben oder Autolacken. Die unterschiedliche Arten von Filtern wirken sich alle anders auf das Foto aus: UV-Filter sch\u00fctzen die Frontlinse der Kamera vor UV-Strahlen, Staub und Kratzern. Sie sind also f\u00fcr den allt\u00e4glichen Schutz und sorgen f\u00fcr klare, scharfe Bilder ohne unerw\u00fcnschte Blaustiche. Grauverlaufsfilter (ND-Filter) reduzieren die einfallende Lichtmenge und erm\u00f6glichen so lange Belichtungszeiten oder eine offene Blende auch bei hellem Tageslicht. Sie sind bestens geeignet f\u00fcr kreative Effekte wie weich flie\u00dfendes Wasser oder Bewegungsunsch\u00e4rfe. Polarisationsfilter minimieren Reflexionen auf metallischen und nichtmetallischen Oberfl\u00e4chen wie Wasser oder Glas und verst\u00e4rken dar\u00fcber hinaus noch die Farben und Kontraste. Sie eignen sich besonders f\u00fcr Landschaftsaufnahmen, Produktfotos oder Aufnahmen bei starkem Sonnenlicht.","og_url":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/filter\/","og_site_name":"Erik Draeger Photography","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/filter\/","url":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/filter\/","name":"Filter Archive - Erik Draeger Photography","isPartOf":{"@id":"https:\/\/erikdraeger.com\/ratgeber\/#website"},"breadcrumb":{"@id":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/filter\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/filter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/erikdraeger.com\/ratgeber\/"},{"@type":"ListItem","position":2,"name":"Zubeh\u00f6r","item":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/"},{"@type":"ListItem","position":3,"name":"Filter"}]},{"@type":"WebSite","@id":"https:\/\/erikdraeger.com\/ratgeber\/#website","url":"https:\/\/erikdraeger.com\/ratgeber\/","name":"Erik Draeger Photography","description":"Ratgeber f\u00fcr Kamera, Objektiv &amp; Zubeh\u00f6r","publisher":{"@id":"https:\/\/erikdraeger.com\/ratgeber\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/erikdraeger.com\/ratgeber\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/erikdraeger.com\/ratgeber\/#organization","name":"Erik Draeger Photography","url":"https:\/\/erikdraeger.com\/ratgeber\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/erikdraeger.com\/ratgeber\/#\/schema\/logo\/image\/","url":"https:\/\/erikdraeger.com\/ratgeber\/wp-content\/uploads\/2023\/11\/cropped-ed-ratgeber-title-2-inverted.jpg","contentUrl":"https:\/\/erikdraeger.com\/ratgeber\/wp-content\/uploads\/2023\/11\/cropped-ed-ratgeber-title-2-inverted.jpg","width":1051,"height":211,"caption":"Erik Draeger Photography"},"image":{"@id":"https:\/\/erikdraeger.com\/ratgeber\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/erikdraeger.com\/ratgeber\/wp-json\/wp\/v2\/categories\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erikdraeger.com\/ratgeber\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/erikdraeger.com\/ratgeber\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/erikdraeger.com\/ratgeber\/wp-json\/wp\/v2\/categories\/10"}],"wp:post_type":[{"href":"https:\/\/erikdraeger.com\/ratgeber\/wp-json\/wp\/v2\/posts?categories=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}