{"id":48,"count":4,"description":"","link":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/walimex\/","name":"Walimex","slug":"walimex","taxonomy":"category","parent":10,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Walimex Archive - Erik Draeger Photography<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/walimex\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walimex Archive - Erik Draeger Photography\" \/>\n<meta property=\"og:url\" content=\"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/walimex\/\" \/>\n<meta property=\"og:site_name\" content=\"Erik Draeger Photography\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/category\\\/zubehoer\\\/walimex\\\/\",\"url\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/category\\\/zubehoer\\\/walimex\\\/\",\"name\":\"Walimex Archive - Erik Draeger Photography\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/category\\\/zubehoer\\\/walimex\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/category\\\/zubehoer\\\/walimex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zubeh\u00f6r\",\"item\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/category\\\/zubehoer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Walimex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#website\",\"url\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/\",\"name\":\"Erik Draeger Photography\",\"description\":\"Ratgeber f\u00fcr Kamera, Objektiv &amp; Zubeh\u00f6r\",\"publisher\":{\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#organization\",\"name\":\"Erik Draeger Photography\",\"url\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-ed-ratgeber-title-2-inverted.jpg\",\"contentUrl\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-ed-ratgeber-title-2-inverted.jpg\",\"width\":1051,\"height\":211,\"caption\":\"Erik Draeger Photography\"},\"image\":{\"@id\":\"https:\\\/\\\/erikdraeger.com\\\/ratgeber\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Walimex Archive - Erik Draeger Photography","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/walimex\/","og_locale":"de_DE","og_type":"article","og_title":"Walimex Archive - Erik Draeger Photography","og_url":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/walimex\/","og_site_name":"Erik Draeger Photography","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/walimex\/","url":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/walimex\/","name":"Walimex Archive - Erik Draeger Photography","isPartOf":{"@id":"https:\/\/erikdraeger.com\/ratgeber\/#website"},"breadcrumb":{"@id":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/walimex\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/walimex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/erikdraeger.com\/ratgeber\/"},{"@type":"ListItem","position":2,"name":"Zubeh\u00f6r","item":"https:\/\/erikdraeger.com\/ratgeber\/category\/zubehoer\/"},{"@type":"ListItem","position":3,"name":"Walimex"}]},{"@type":"WebSite","@id":"https:\/\/erikdraeger.com\/ratgeber\/#website","url":"https:\/\/erikdraeger.com\/ratgeber\/","name":"Erik Draeger Photography","description":"Ratgeber f\u00fcr Kamera, Objektiv &amp; Zubeh\u00f6r","publisher":{"@id":"https:\/\/erikdraeger.com\/ratgeber\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/erikdraeger.com\/ratgeber\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/erikdraeger.com\/ratgeber\/#organization","name":"Erik Draeger Photography","url":"https:\/\/erikdraeger.com\/ratgeber\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/erikdraeger.com\/ratgeber\/#\/schema\/logo\/image\/","url":"https:\/\/erikdraeger.com\/ratgeber\/wp-content\/uploads\/2023\/11\/cropped-ed-ratgeber-title-2-inverted.jpg","contentUrl":"https:\/\/erikdraeger.com\/ratgeber\/wp-content\/uploads\/2023\/11\/cropped-ed-ratgeber-title-2-inverted.jpg","width":1051,"height":211,"caption":"Erik Draeger Photography"},"image":{"@id":"https:\/\/erikdraeger.com\/ratgeber\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/erikdraeger.com\/ratgeber\/wp-json\/wp\/v2\/categories\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erikdraeger.com\/ratgeber\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/erikdraeger.com\/ratgeber\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/erikdraeger.com\/ratgeber\/wp-json\/wp\/v2\/categories\/10"}],"wp:post_type":[{"href":"https:\/\/erikdraeger.com\/ratgeber\/wp-json\/wp\/v2\/posts?categories=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}